{"id":52,"count":1,"description":"","link":"https:\/\/e-scooterlife.co.uk\/index.php\/tag\/vigo\/","name":"Vigo","slug":"vigo","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vigo Archives - E-Scooter Life<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-scooterlife.co.uk\/index.php\/tag\/vigo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vigo Archives - E-Scooter Life\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-scooterlife.co.uk\/index.php\/tag\/vigo\/\" \/>\n<meta property=\"og:site_name\" content=\"E-Scooter Life\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/e-scooterlife.co.uk\\\/index.php\\\/tag\\\/vigo\\\/\",\"url\":\"https:\\\/\\\/e-scooterlife.co.uk\\\/index.php\\\/tag\\\/vigo\\\/\",\"name\":\"Vigo Archives - E-Scooter Life\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-scooterlife.co.uk\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/e-scooterlife.co.uk\\\/index.php\\\/tag\\\/vigo\\\/#breadcrumb\"},\"inLanguage\":\"en\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/e-scooterlife.co.uk\\\/index.php\\\/tag\\\/vigo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/e-scooterlife.co.uk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vigo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/e-scooterlife.co.uk\\\/#website\",\"url\":\"https:\\\/\\\/e-scooterlife.co.uk\\\/\",\"name\":\"E-Scooter Life\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/e-scooterlife.co.uk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vigo Archives - E-Scooter Life","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-scooterlife.co.uk\/index.php\/tag\/vigo\/","og_locale":"en_US","og_type":"article","og_title":"Vigo Archives - E-Scooter Life","og_url":"https:\/\/e-scooterlife.co.uk\/index.php\/tag\/vigo\/","og_site_name":"E-Scooter Life","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/e-scooterlife.co.uk\/index.php\/tag\/vigo\/","url":"https:\/\/e-scooterlife.co.uk\/index.php\/tag\/vigo\/","name":"Vigo Archives - E-Scooter Life","isPartOf":{"@id":"https:\/\/e-scooterlife.co.uk\/#website"},"breadcrumb":{"@id":"https:\/\/e-scooterlife.co.uk\/index.php\/tag\/vigo\/#breadcrumb"},"inLanguage":"en"},{"@type":"BreadcrumbList","@id":"https:\/\/e-scooterlife.co.uk\/index.php\/tag\/vigo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/e-scooterlife.co.uk\/"},{"@type":"ListItem","position":2,"name":"Vigo"}]},{"@type":"WebSite","@id":"https:\/\/e-scooterlife.co.uk\/#website","url":"https:\/\/e-scooterlife.co.uk\/","name":"E-Scooter Life","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-scooterlife.co.uk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"}]}},"_links":{"self":[{"href":"https:\/\/e-scooterlife.co.uk\/index.php\/wp-json\/wp\/v2\/tags\/52","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-scooterlife.co.uk\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/e-scooterlife.co.uk\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/e-scooterlife.co.uk\/index.php\/wp-json\/wp\/v2\/posts?tags=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}